{"id":9666,"date":"2025-10-28T10:45:14","date_gmt":"2025-10-28T06:45:14","guid":{"rendered":"https:\/\/azuri.mu\/nachhaltigkeit\/"},"modified":"2026-08-19T15:44:27","modified_gmt":"2026-08-19T11:44:27","slug":"nachhaltigkeit","status":"publish","type":"page","link":"https:\/\/azuri.mu\/de\/das-dorf\/nachhaltigkeit\/","title":{"rendered":"Nachhaltigkeit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9666\" class=\"elementor elementor-9666 elementor-2349\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/2025\/10\/Sustainability-Hero.jpg\" class=\"elementor-element elementor-element-12b39c8 lazy-bg e-flex e-con-boxed e-con e-parent\" data-id=\"12b39c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ddfd3c2 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ddfd3c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bauen im Einklang mit der Natur<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f888f8 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0f888f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset_tablet&quot;:0,&quot;sticky_offset_mobile&quot;:0,&quot;sticky_effects_offset&quot;:125,&quot;sticky_effects_offset_tablet&quot;:100,&quot;sticky_effects_offset_mobile&quot;:75,&quot;sticky_anchor_link_offset_tablet&quot;:0,&quot;sticky_anchor_link_offset_mobile&quot;:0,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIn Azuri ist Nachhaltigkeit kein abstraktes Konzept, sondern gelebte Praxis im Alltag. <br class=\"desktop-break\"><br class=\"tablet-break\">Das Dorf w\u00e4chst im Einklang mit der Natur und verbindet Innovation, Respekt und Weitergabe f\u00fcr die Zukunft.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/2025\/10\/les-meleanes-intro-gradient.jpg\" class=\"elementor-element elementor-element-a78d6e0 lazy-bg e-flex e-con-boxed e-con e-parent\" data-id=\"a78d6e0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-05d364c e-con-full e-flex e-con e-child\" data-id=\"05d364c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0763f94 e-con-full e-flex e-con e-child\" data-id=\"0763f94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7081fa animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d7081fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nachhaltigkeit <br \/><span class=\"weight-900\">in Azuri Village<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4596cd5 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4596cd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSeit seiner Gr\u00fcndung setzt sich Azuri daf\u00fcr ein, ein nachhaltiges Dorf zu schaffen, in dem sich Natur und Gemeinschaft gegenseitig bereichern. Es ist mehr als nur ein Ort zum Leben. Es ist ein auf Nachhaltigkeit ausgelegtes \u00d6kosystem, in dem jede Entscheidung Umweltverantwortung und Lebensqualit\u00e4t verbindet. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fce7602 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fce7602\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tMit 13% des Areals, das Gr\u00fcnfl\u00e4chen gewidmet sind \u2013 weit mehr als die vom Smart City Scheme geforderten 4% \u2013 ist der Naturschutz fest in unserer DNA verankert. Parks, heimische W\u00e4lder, Gew\u00e4sser und Gr\u00fcnkorridore bilden eine lebendige Landschaft, die die Artenvielfalt und das Wohlbefinden f\u00f6rdert. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab2db97 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ab2db97\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tUnsere Infrastruktur folgt derselben Logik und verfolgt einen ressourcenschonenden Ansatz. Regenwasser wird durch Versickerungsmulden und R\u00fcckhaltebecken geleitet, \u00f6koeffiziente Materialien werden bevorzugt eingesetzt, erneuerbare Energiequellen integriert, und das Stra\u00dfennetz wurde mit dem neuen Kreisverkehr verbessert. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34140b1 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"34140b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJede Initiative verfolgt ein klares Ziel: Azuri zu einem Vorbild f\u00fcr ein resilientes Dorf zu machen, in dem heutige und zuk\u00fcnftige Generationen ein ausgewogenes, inspirierendes und nachhaltiges Umfeld teilen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/2025\/10\/sustanability-gradient-bg.png\" class=\"elementor-element elementor-element-67d915a lazy-bg e-flex e-con-boxed e-con e-parent\" data-id=\"67d915a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e2a894e e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"e2a894e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/2025\/10\/Gestion-des-ressources.jpg\" class=\"elementor-element elementor-element-c665628 e-con-full lazy-bg e-flex e-con e-child\" data-id=\"c665628\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-color=\"#F7F7F7\" class=\"elementor-element elementor-element-3de12a3 e-con-full e-flex e-con e-child\" data-id=\"3de12a3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6398a13 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6398a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Intelligentes\nWohnen<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b026e3d animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b026e3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIn Azuri zeigt sich urbane Intelligenz in einer Gestaltung, die nat\u00fcrliche Ressourcen in den Vordergrund stellt. Die Ausrichtung der Geb\u00e4ude, die Querl\u00fcftung und die \u00d6ffnung der Wohnviertel f\u00fcr die Brise reduzieren den Einsatz von Klimaanlagen erheblich und senken so den CO\u2082-Fu\u00dfabdruck und den Energieverbrauch. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9f3144 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e9f3144\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDas t\u00e4gliche Leben wird dadurch ver\u00e4ndert: Eine nat\u00fcrliche Brise k\u00fchlt die Innenr\u00e4ume, die \u00f6ffentlichen Bereiche atmen, und Komfort entsteht, ohne dass mechanische Systeme \u00fcberm\u00e4\u00dfig eingesetzt werden m\u00fcssen. Das Konzept \u201eSmart Living\u201c bedeutet, im Einklang mit der Natur zu bauen und dabei schlichte, effiziente L\u00f6sungen zu integrieren, die das Wohlbefinden der Bewohner gew\u00e4hrleisten und gleichzeitig die kollektive Widerstandsf\u00e4higkeit des Dorfes st\u00e4rken. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6e2789 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"b6e2789\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div data-dce-background-color=\"#F7F7F7\" class=\"elementor-element elementor-element-401aff7 e-con-full e-flex e-con e-child\" data-id=\"401aff7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a481f9 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a481f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Verbesserung\ndes Stra\u00dfennetzes<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4087d67 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4087d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIn Azuri zeigt sich Nachhaltigkeit auch in der Art und Weise, wie wir uns fortbewegen. Um den Verkehr sicherer und fl\u00fcssiger zu gestalten, wurden am Ortseingang ein neuer Kreisverkehr und eine gesicherte Zufahrt eingerichtet \u2013 eine Investition von rund 41 Millionen Rupien. Aus einem ehemals unfalltr\u00e4chtigen Bereich, der durch Staus und unkontrollierte Zufahrten gekennzeichnet war, ist eine \u00fcbersichtliche und verkehrsberuhigte Kreuzung geworden.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6453ef2 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6453ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDer Verkehrsfluss hat sich sowohl im Dorf als auch auf der Hauptverkehrsachse von Roches Noires verbessert, was den Zugang f\u00fcr Anwohner, Besucher und Dienstleister erleichtert. Die Wartezeiten haben sich verk\u00fcrzt, ebenso wie die Emissionen durch Leerlaufmotoren f\u00fcr eine sicherere und nachhaltigere Mobilit\u00e4t. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/2025\/11\/Website-Roundabout-Sustainability-1.jpg\" class=\"elementor-element elementor-element-4c4342d e-con-full lazy-bg e-flex e-con e-child\" data-id=\"4c4342d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d69666 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"1d69666\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div data-dce-background-image-url=\"https:\/\/azuri.mu\/wp-content\/uploads\/dji_fly_20260304_115846_0119_1772611842161_photo-1.jpg\" class=\"elementor-element elementor-element-2c511cf e-con-full lazy-bg e-flex e-con e-child\" data-id=\"2c511cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-color=\"#F7F7F7\" class=\"elementor-element elementor-element-3e73a01 e-con-full e-flex e-con e-child\" data-id=\"3e73a01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb4ed9 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dbb4ed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Becken und Regenwassermulden f\u00fcr ein besseres Wassermanagement<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b501aea animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b501aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSeit 2012 wird der Masterplan von Azuri weiterentwickelt, um naturbasierte L\u00f6sungen zu integrieren. Das gemeinsam mit Atelier LD und SJPCE konzipierte und 2024 eingef\u00fchrte Rahmenkonzept f\u00fcr das Regenwassermanagement setzt auf Versickerung und Absorption statt auf Beton und unterirdische Leitungsnetze. Ein Kilometer Regenwassermulden entlang der Stra\u00dfen und eine Bio-R\u00fcckhaltefl\u00e4che wandeln Regenwasser in eine Ressource um.   \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f265232 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f265232\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDiese mit den Abflussrinnen verbundenen Anlagen leiten den Abfluss in die richtigen Bahnen, f\u00fcllen die Grundwasservorkommen wieder auf und begrenzen Hochwasser, Erosion und den Eintrag von Schadstoffen in den Ozean. Dieses innovative blau-gr\u00fcne Netzwerk reduziert den W\u00e4rmeinseleffekt, verbessert die Bel\u00fcftung und versorgt in der Trockenzeit Parks und G\u00e4rten. Weitere Initiativen werden diesen nachhaltigen Ansatz bald erg\u00e4nzen.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bauen im Einklang mit der Natur In Azuri ist Nachhaltigkeit kein abstraktes Konzept, sondern gelebte Praxis im Alltag. Das Dorf w\u00e4chst im Einklang mit der Natur und verbindet Innovation, Respekt und Weitergabe f\u00fcr die Zukunft. Nachhaltigkeit in Azuri Village Seit seiner Gr\u00fcndung setzt sich Azuri daf\u00fcr ein, ein nachhaltiges Dorf zu schaffen, in dem sich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9667,"parent":9931,"menu_order":32,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"page-category":[],"class_list":["post-9666","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/pages\/9666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/comments?post=9666"}],"version-history":[{"count":3,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/pages\/9666\/revisions"}],"predecessor-version":[{"id":10562,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/pages\/9666\/revisions\/10562"}],"up":[{"embeddable":true,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/pages\/9931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/media\/9667"}],"wp:attachment":[{"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/media?parent=9666"}],"wp:term":[{"taxonomy":"page-category","embeddable":true,"href":"https:\/\/azuri.mu\/de\/wp-json\/wp\/v2\/page-category?post=9666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}